{"id":12044,"date":"2024-03-27T18:31:26","date_gmt":"2024-03-27T17:31:26","guid":{"rendered":"http:\/\/santagostinorimini.it\/new_sito\/?p=12044"},"modified":"2024-03-27T19:13:07","modified_gmt":"2024-03-27T18:13:07","slug":"san-giovanni-da-san-facondo-2","status":"publish","type":"post","link":"https:\/\/santagostinorimini.it\/new_sito\/2024\/03\/27\/san-giovanni-da-san-facondo-2\/","title":{"rendered":"San Giovanni da San Facondo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"699\" height=\"1024\" src=\"http:\/\/santagostinorimini.it\/new_sito\/wp-content\/uploads\/2024\/03\/sangiovannidasanfacondo-1-699x1024.jpg\" alt=\"\" class=\"wp-image-11795\" style=\"width:840px;height:auto\" srcset=\"https:\/\/santagostinorimini.it\/new_sito\/wp-content\/uploads\/2024\/03\/sangiovannidasanfacondo-1-699x1024.jpg 699w, https:\/\/santagostinorimini.it\/new_sito\/wp-content\/uploads\/2024\/03\/sangiovannidasanfacondo-1-205x300.jpg 205w, https:\/\/santagostinorimini.it\/new_sito\/wp-content\/uploads\/2024\/03\/sangiovannidasanfacondo-1-768x1125.jpg 768w, https:\/\/santagostinorimini.it\/new_sito\/wp-content\/uploads\/2024\/03\/sangiovannidasanfacondo-1-1048x1536.jpg 1048w, https:\/\/santagostinorimini.it\/new_sito\/wp-content\/uploads\/2024\/03\/sangiovannidasanfacondo-1-1398x2048.jpg 1398w, https:\/\/santagostinorimini.it\/new_sito\/wp-content\/uploads\/2024\/03\/sangiovannidasanfacondo-1-scaled.jpg 1747w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><\/figure>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#fbeedd\"><em>Pozo Amarillo, era un pozzo nel quale ai tempi del santo cadde un fanciullo. Il pozzo era profondo ma Juan vi gett\u00f2 la sua cintura: l&#8217;acqua sal\u00ec fino a permettere al piccolo di aggrapparsi ad essa e salvarsi.<\/em><\/p>\n\n\n\n<h1 class=\"wp-block-heading\">San Juan de Sahagun<br>sacerdote eremita agostiniano (1430-1479)<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Juan de Sahagun, San<\/strong>&nbsp;.&nbsp;<em>Apostolo di Salamanca<\/em>&nbsp;.&nbsp;Sahag\u00fan (Le\u00f3n), 1429-1431 \u2013 Salamanca, 11.VI.1479.&nbsp;Agostiniano (OSA), taumaturgo, predicatore generale, santo.<em><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era il figlio di Juan Gonz\u00e1lez de Castrillo e Sancha Mart\u00ednez, nobili;&nbsp;originario della cittadina leonese di Sahag\u00fan, sede della famosa abbazia benedettina edificata sulla tomba dei fratelli martiri del III secolo Facundo e Primitivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nacque probabilmente tra gli anni 1429 e 1431, esaudendo il desiderio di una discendenza dei suoi genitori, che andarono a richiederla a Nuestra Se\u00f1ora de la Puente, nel suo eremo romanico vicino al fiume Valderaduey, sulla strada per la Francia;&nbsp;Successivamente arriveranno altri sei figli, tra cui Hernando, che sar\u00e0 benedettino e arcivescovo di Granada prima della conquista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nella gi\u00e0 citata abbazia benedettina del Santo Domnos erano stati eretti gli Studi Generali dove si insegnavano gli insegnamenti del Trivio medievale delle scuole monastiche ed altre materie;&nbsp;Fu in quell&#8217;ambiente accademico che, in quanto primogenito, Juan comp\u00ec i primi studi e plasm\u00f2 la sua volont\u00e0 acquisendo anche altre qualit\u00e0;&nbsp;Scopr\u00ec la vocazione allo stato clericale e prosegu\u00ec gli studi di Teologia con il piacere del padre, che gli ottenne il beneficio ecclesiastico con una cura d&#8217;anime, a Cordonillos, ma con al suo servizio un cappellano, al quale rinunci\u00f2 per scrupolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Date le risorse limitate di una famiglia cos\u00ec numerosa e le qualit\u00e0 del giovane Juan, tramite suo zio Juan Alfonso, fratello di suo padre e amico personale dell&#8217;arcivescovo, gli cercarono un posto a Burgos e lui divenne cameriere del prelato, il si distinse Alonso de Cartagena, nel cui palazzo trov\u00f2 un ambiente favorevole alla coltivazione della letteratura umana e divina, terminando gli studi ecclesiastici.&nbsp;Una volta ordinato sacerdote, il vescovo lo dot\u00f2 delle entrate di alcuni benefici ecclesiastici &#8211; aggiunti ad altri che gli aveva concesso l&#8217;abate del monastero di Sahag\u00fan &#8211; e premi\u00f2 le attitudini che aveva maturato come suo parente con un canonico nella santa cattedrale chiesa, non conoscendo nel giovane sacerdote altro cambiamento se non quello di servire la sua vocazione nella cura delle anime affidategli mediante la predicazione, nella quale cominciava gi\u00e0 a mostrare segni di ottimo coltivatore, e il desiderio di restare vicino al libri che svilupparono la mente e lo avvicinarono a Dio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sebbene avesse una buona posizione ecclesiastica, non era quello che cercava;&nbsp;Rinunci\u00f2 a tutte le cariche e vantaggi e si ritir\u00f2 in cappellania nella chiesa di Burgos di Santa Gadea (\u00c1gata), con tante risonanze cidiane e nobili.&nbsp;Fu in questo periodo che acquist\u00f2 la&nbsp;&nbsp;<em>Suma bartolina&nbsp;<\/em>&nbsp;(maggio 1456) dai frati di San Pablo a Burgos, dove in seguito poser\u00e0 alcuni appunti che sono gli unici suoi scritti sopravvissuti fino ai giorni nostri.&nbsp;Pochi mesi dopo il cambiamento nella sua vita, mor\u00ec l&#8217;arcivescovo Alonso di Cartagena, che era stato padre e maestro di Juan, ed egli si sent\u00ec pi\u00f9 libero di trasferirsi a Salamanca;&nbsp;Voleva continuare i suoi studi all&#8217;Universit\u00e0 e sperava di potersi mantenere prestando servizio in una chiesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Salamanca del XV secolo era una citt\u00e0 di studi, la cui Universit\u00e0 era basata sui collegi;&nbsp;Era una citt\u00e0 levitica strutturata da una moltitudine di conventi di tutti gli ordini religiosi;&nbsp;Era una citt\u00e0 forte, cinta da mura e torreggiata dai palazzi di importanti famiglie nobili.&nbsp;Il sacerdote di Burgos dovette arrivarvi nel 1457, anno probabile della sua iscrizione all&#8217;Universit\u00e0.&nbsp;Nella parrocchia di San Sebasti\u00e1n, nella cui collazione si trovava il collegio principale di San Bartolom\u00e9, questo centro celebr\u00f2 la festa del proprietario del tempio nell&#8217;anno 1458, di cui il collegio era patrono, con il sacerdote studente Juan de Sahag\u00fan, che dovevano gi\u00e0 conoscere bene per offrirgli un incarico cos\u00ec importante;&nbsp;Si sa dalle cronache che il rettore, i consiglieri e gli scolari furono commossi dalla predica ascoltata al punto da offrire loro, pochi giorni dopo, l&#8217;incarico di cappellano &#8211; c&#8217;erano due cappellanie scolastiche &#8211; nel sindaco di San Bartolom\u00e9, che aveva \u00e8 stata fondata quasi mezzo secolo da Diego de Anaya Maldonado, arcivescovo di Siviglia, secondo il modello del Real Collegio di Spagna o San Clemente de los Espa\u00f1oles di Bologna (Italia), fondato dal cardinale Gil de Albornoz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00ec ritrov\u00f2 i due spazi in cui rafforz\u00f2 la sua esistenza: cappella e biblioteca;&nbsp;Oltre ai compiti collegiali e accademici, Juan si sent\u00ec obbligato come sacerdote a non ignorare anche altri problemi.&nbsp;Si cercava la sua parola per chiedere consiglio, per ascoltarlo predicare, per amministrare i sacramenti.&nbsp;Un grave problema urbano che divise e fece sanguinare la citt\u00e0 fu la divisione e lo scontro tra alcune importanti famiglie, rendendo questi schieramenti e le loro lotte una triste realt\u00e0 quotidiana.&nbsp;In mezzo a loro, Juan non ha smesso di lavorare e di chiedere la fine delle ostilit\u00e0, l&#8217;oblio dell&#8217;uso delle armi, sostenendo la fine della lotta.&nbsp;Le loro preghiere e le loro penitenze, le loro parole e la loro dedizione hanno permesso che arrivasse la pace e emergesse la riconciliazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli orari rigidi e la disciplina costituzionale del collegio divennero incompatibili con il suo intenso atteggiamento apostolico, tanto che dovette rinunciare all&#8217;incarico di cappellano, ma le porte non gli furono chiuse;&nbsp;And\u00f2 a vivere nella casa di Pedro S\u00e1nchez, canonico della cattedrale e molto amato dai salamancani, e il Consiglio fu incaricato di prendersi cura del suo mantenimento nominandolo predicatore della citt\u00e0, incarico che cerc\u00f2 di portare avanti con dottrina, con l\u2019esempio e con il desiderio di essere sempre pronti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per anni soffr\u00ec della malattia dei calcoli, che a volte lo lasciava prostrato e soffriva di dolori acuti;&nbsp;La situazione peggior\u00f2 fino ad arrivare al momento critico di mettere in pericolo la sua vita.&nbsp;La soluzione di un intervento, quindi, era rischiosa e pericolosa;&nbsp;I medici Medina e Recio il maggiore lo proposero come alternativa all&#8217;esito finale che si avvicinava.&nbsp;Era un uomo di fede che affrontava in modo particolare le questioni vitali;&nbsp;Si affid\u00f2 a Dio e fece voto che, se fosse guarito, avrebbe trovato il modo di servirlo nella vita religiosa.&nbsp;Dopo aver subito il tormento di un intervento chirurgico abbastanza elementare, si \u00e8 ripreso dall&#8217;intervento e ha riacquistato la salute come un dono che Dio gli ha fatto;&nbsp;Anche in quei giorni visse un&#8217;intima e intensa esperienza religiosa di cui non volle mai parlare nei dettagli, tra Dio e la sua anima, e decise di mantenere la promessa fatta entrando in quella citt\u00e0 nel convento di San Agust\u00edn, gi\u00e0 assegnato a l&#8217;osservanza di Castiglia, casa leader nella scienza e nella virt\u00f9, che tradizionalmente sarebbe conosciuta come il convento dei santi e dei saggi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il 18 giugno 1563 vest\u00ec l&#8217;abito ed emise la professione il 28 agosto dell&#8217;anno successivo.&nbsp;La dedizione di Fray Juan nel fare bene tutto ci\u00f2 che doveva fare, e nel farlo con gioia, attir\u00f2 la nostra attenzione;&nbsp;Non c&#8217;erano radicalismi e posizioni estreme, che erano sempre la tentazione subita dalle persone mature della vita clericale che venivano al chiostro.&nbsp;Ha adempiuto puntualmente ai suoi obblighi personali e comunitari, dove spesso risiede la virt\u00f9.&nbsp;Per due volte sar\u00e0 eletto priore della comunit\u00e0 di Salamanca (1471 e 1477) e definitore provinciale (1471).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salamanca rimase costernata dalla morte a tradimento dei nobili fratelli Enr\u00edquez Monroy (Pedro e Luis) per mano dei Manzano e dei loro servi, anch&#8217;essi nobili, intorno al 1464 o 1465;&nbsp;Rimase stupito dalla freddezza con cui la madre vedova accolse la notizia, i corpi senza vita dei suoi figli piccoli e la punizione della confisca dei beni degli assassini ordinata da Enrico IV.&nbsp;Mentre i cadaveri erano ancora quasi caldi, attravers\u00f2 la frontiera portoghese con un gruppo di venti servi finch\u00e9 non trov\u00f2 il luogo in cui si erano nascosti i colpevoli e applic\u00f2 loro la giustizia del sangue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;intera citt\u00e0 rimase scioccata quando seppe che Mar\u00eda de Monroy era tornata con le teste dei Manzano (G\u00f3mez e Alonso) e come trofeo di vendetta le aveva deposte sulla tomba dei suoi figli;&nbsp;Da allora fu conosciuta come \u201cDo\u00f1a Mar\u00eda, la Brava\u201d.&nbsp;La lotta tra famiglie e clan ricominci\u00f2, pi\u00f9 dura di prima, finch\u00e9 la citt\u00e0 \u2013 Comuni, Universit\u00e0, parrocchie \u2013 si trov\u00f2 divisa in due schieramenti inconciliabili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le autorit\u00e0 si rivolsero al frate agostiniano Juan de Sahag\u00fan per trovare una soluzione;&nbsp;Ci sono volute preghiera e azione.&nbsp;Parl\u00f2, predic\u00f2 e escogit\u00f2 formule di riavvicinamento tra loro, approfittando del fatto che tutti lo cercavano;&nbsp;Le parole e gli sforzi dei religiosi hanno trionfato, ottenendo il perdono di tutti e l&#8217;impegno a rinunciare alla vendetta e alla violenza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La riconciliazione si fond\u00f2 su una concordia concordata e ratificata pubblicamente dai rappresentanti delle parti (Maldonado, Acebedo, Nieto, Anaya, Arias, Enr\u00edquez&#8230;), e padre Juan fu riconosciuto come un angelo di pace;&nbsp;Nell&#8217;esercizio della sua vita apostolica dovette superare anche la violenza contro la sua persona e le sue azioni, ad esempio con i capi di Ledesma e con lo stesso Duca d&#8217;Alba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Che Dio abbia compiuto azioni speciali nella sua vita e per mano di Fratel Juan de Sahag\u00fan, \u00e8 qualcosa che gli abitanti di Salamanca sapevano e hanno lasciato abbondanti testimonianze come testimonianze, in racconti, iscrizioni, bassorilievi, ecc., che poco dopo la sua morte \u00e8 entrato a far parte dell&#8217;informazione di molti testimoni che hanno testimoniato nei processi di beatificazione e canonizzazione.&nbsp;Negli annali della storia di Salamanca ricordiamo il prodigio compiuto dal santo nel \u201cpozzo giallo\u201d, dove, dopo che un bambino era caduto nelle profondit\u00e0 di un pozzo, riusc\u00ec a salvarlo facendo risalire le acque fino a il bordo e restituirlo con la vita alla madre sconvolta;&nbsp;Vicino alla vecchia cattedrale, la via Tente Necio evoca anche il fatto che, dopo essere fuggito da quel quartiere, un toro coraggioso spavent\u00f2 i vicini finch\u00e9 non intervenne frate Juan e lo addomestic\u00f2 con quell&#8217;espressione \u2014\u201ctenda, sciocco\u201d\u2014, restituendo tranquillit\u00e0 alla zona. gente di quelle strade;&nbsp;e nei processi sono tante altre le azioni taumaturgiche compiute attraverso il suo intervento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pochi giorni dopo aver terminato il suo secondo convento si ammal\u00f2 improvvisamente, si sparse la voce che ci\u00f2 fosse dovuto ad aver ingerito qualcosa di velenoso;&nbsp;Le fatiche sofferte avevano stremato il suo corpo e la sua vita mortale termin\u00f2 l&#8217;11 giugno 1479. Le manifestazioni di lutto in tutta la citt\u00e0 dimostrarono ci\u00f2 che fratel Juan de Sahag\u00fan era stato per Salamanca.&nbsp;Inizialmente fu sepolto sotto il coro della chiesa conventuale di San Agust\u00edn di quella citt\u00e0;&nbsp;La sua tomba divenne un luogo di pellegrinaggio, dove le persone accorrevano in cerca di aiuto e intercessione, e si sa che molte volte furono ascoltate.&nbsp;Nel 1578 le spoglie furono deposte in una nuova e bella cappella;&nbsp;Sull\u2019urna sepolcrale che conteneva le venerate reliquie fu posto un laconico epitaffio che riassumeva la loro dedizione a Salamanca e che rimase a lungo: \u201cHic jacet per quam Salmantica non jacet\u201d (\u201cQui giace per chi Salamanca non mente\u201d) .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le vicissitudini della vita del convento &#8211; incendi del 1589 e del 1744 &#8211; non danneggiarono le reliquie perch\u00e9 gli Agostiniani le salvarono come un tesoro prezioso, e le vicende storiche vissute in citt\u00e0 nelle diverse esclaustrazioni, nel 1821 e nel 1835, ne influirono destino. .&nbsp;Il 1\u00b0 settembre 1835 le venerate reliquie furono traslate nella cappella maggiore della nuova cattedrale, dove riposano nell&#8217;urna d&#8217;argento donata dalla citt\u00e0, su un piedistallo d&#8217;argento pagato dal convento degli Agostiniani, entrambi pezzi realizzati per il occasione della sua canonizzazione;&nbsp;quella di San Giovanni di Sahag\u00fan appare sul lato destro, o il Vangelo, e sul lato sinistro o l&#8217;Epistola, in un&#8217;altra urna identica, riposano le reliquie di suo fratello San Tommaso di Villanueva, anch&#8217;egli priore del convento agostiniano alcuni decenni dopo . .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fu beatificato da Clemente VIII il 19 giugno 1601 e canonizzato da Alessandro VIII il 16 ottobre 1690, anche se, a causa della morte del Papa, la bolla fu pubblicata dal suo successore Innocenzo XII il 15 luglio 1691.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La citt\u00e0 di Salamanca lo celebr\u00f2 con solenni feste barocche come tante furono organizzate in Spagna nel XVI secolo, di cui furono stampate ampie cronache degli eventi;&nbsp;I consigli di Salamanca e della sua citt\u00e0 natale di Sahag\u00fan proclamarono San Giovanni patrono, e la facolt\u00e0 dell&#8217;Universit\u00e0, di cui era stato studente, istituirono il 12 giugno come festa accademica in tutte le sue scuole, in cui ne commemorava la festa liturgica. .&nbsp;Successivamente lo proclamarono santo patrono anche la diocesi di Salamanca, la provincia agostiniana di Spagna e le viceprovince di Brasile e Argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Opere di ~: \u201cNote marginali su passi della Bibbia posti nella&nbsp;&nbsp;<em>Summa Bartolina&nbsp;<\/em>&nbsp;(di Bartolom\u00e9 da Pisa)\u201d, in T. de Herrera,&nbsp;&nbsp;<em>Historia del Convento de San Agust\u00edn de Salamanca,&nbsp;<\/em>&nbsp;Madrid, 1652, pp.&nbsp;74-78, e in T. de C\u00e1mara,&nbsp;&nbsp;<em>Vita di San Juan de Sah\u00fan dell&#8217;Ordine di San Agust\u00edn Patrono di Salamanca,&nbsp;<\/em>&nbsp;Salamanca, Calatrava, 1891, pp.&nbsp;357-366;&nbsp;<em>Confessioni&nbsp;<\/em>&nbsp;(sparizione).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bibl.: J. de Sevilla,&nbsp;&nbsp;<em>Vida del Santo Fray Juan de Sahag\u00fan,&nbsp;<\/em>&nbsp;Salamanca, 1496 [tradotto in latino (Bolandistas) e tedesco (A. Witte, 1691)];&nbsp;A. de Orozco,&nbsp;&nbsp;<em>Cr\u00f3nica de NP San Agust\u00edn,&nbsp;<\/em>&nbsp;Siviglia, 1551 (nuova ed. di M. Gonz\u00e1lez, Madrid 2001, pp. XLIII, LVIII, LXXXIV, 33, 194-199 e 445-446);&nbsp;F. Ruiz de Vergara, \u201cDel Beato San Juan de Sah\u00fan\u201d, in&nbsp;&nbsp;<em>Storia dell&#8217;Antica Scuola di San Bartolom\u00e9,&nbsp;<\/em>&nbsp;Salamanca, 1555;&nbsp;J. Rom\u00e1n,&nbsp;&nbsp;<em>Chronica dell&#8217;Ordine degli Eremiti del Glorioso Padre Sancto August\u00edn, II Centuria,&nbsp;<\/em>&nbsp;Salamanca 1569;&nbsp;A. de Orozco,&nbsp;&nbsp;<em>Libro della vita del beato San Giovanni di Sahag\u00fan,&nbsp;<\/em>&nbsp;Valladolid, 1570;&nbsp;J. Rom\u00e1n, \u201cVita di San Juan de Sahag\u00fan\u201d, nella&nbsp;&nbsp;<em>Prima parte della storia dell&#8217;ordine dei frati eremo di Sant Agust\u00edn,&nbsp;<\/em>&nbsp;Alcal\u00e1, 1572;&nbsp;J. de Marietta,&nbsp;&nbsp;<em>Storia dei Santi di Spagna,&nbsp;<\/em>&nbsp;Cuenca, 1595;&nbsp;Cardinale Antoniani,&nbsp;&nbsp;<em>Super vita, sanctitate et miraculis Beati Joannis a Sancto Facundo,&nbsp;<\/em>&nbsp;Romae, 1600;&nbsp;Clemente VIII, \u201cBreve di beatificazione di Juan de Sahag\u00fan, 1601\u201d, in&nbsp;&nbsp;<em>Vita,&nbsp;<\/em>&nbsp;di T. C\u00e1mara (OC), pp.&nbsp;241-244;&nbsp;J. Ca\u00f1ete Cabeza de Vaca,&nbsp;&nbsp;<em>L&#8217;iride della pace di Salamanca, San Juan de Sahag\u00fan (Conversazione storica e allegorica in un atto)&nbsp;<\/em>&nbsp;(Biblioteca Nazionale, Madrid, ms. 17400, XVIII secolo);&nbsp;J. de Armend\u00e1riz,&nbsp;&nbsp;<em>Patrono Salmantino,&nbsp;<\/em>&nbsp;Salamanca, 1603 (Barcellona, \u200b\u200b1622, Roma, 1611 e 1645);&nbsp;A. Antol\u00ednez,&nbsp;&nbsp;<em>Vita di San Juan de Sahag\u00fan,&nbsp;<\/em>&nbsp;Salamanca, 1605;&nbsp;G. Gonz\u00e1lez D\u00e1vila,&nbsp;&nbsp;<em>Vita del pi\u00f9 glorioso patrono di questa citt\u00e0 di Salamanca, San Juan de Sahag\u00fan dell&#8217;ordine di San Agust\u00edn,&nbsp;<\/em>&nbsp;Salamanca, 1606;&nbsp;P. de Mariz,&nbsp;&nbsp;<em>Hist\u00f3ria do bem-aventurado S\u00e2o Jo\u00e2o de Sahagum, Patr\u00e2o Salmantino,&nbsp;<\/em>&nbsp;Lisbona, 1609;&nbsp;G. Maigrett,&nbsp;&nbsp;<em>La vie du bien-heureux de Sahagoune de l&#8217;orde des eremites du PS Augustin,&nbsp;<\/em>&nbsp;Tournay, 1610;&nbsp;A. Osorio,&nbsp;&nbsp;<em>Storia della vita e dei miracoli di Padre San Juan de Santo Facundo,&nbsp;<\/em>&nbsp;Barcellona 1614;&nbsp;P. Frasinelli,&nbsp;&nbsp;<em>Historia della vita e miracoli del beato Giovanni di San Facondo, dell&#8217;Ordine di S. Agostino,&nbsp;<\/em>&nbsp;Bologna 1615 (testo di A. Antol\u00ednez);&nbsp;A. Antol\u00ednez,&nbsp;&nbsp;<em>Miracolo compiuto da Dio nostro Signore [&#8230;] per intercessione del beato Sam Juan de Sah\u00fan [&#8230;],&nbsp;<\/em>&nbsp;Salamanca, 1622;&nbsp;N. Baxi,&nbsp;&nbsp;<em>Vita B. Joannis Sahaguntini, gi\u00e0 Ordine FF.&nbsp;Ehm.&nbsp;S. Agostino,&nbsp;<\/em>&nbsp;Antuerpiae, 1625;&nbsp;A. de la Calancha,&nbsp;&nbsp;<em>Cronaca moralizzata dell&#8217;Ordine di Sant&#8217;Agostino in Per\u00f9,&nbsp;<\/em>&nbsp;Barcellona, \u200b\u200b1638 e 1639 (Lima, 1657; ed. di M. Merino, Madrid, 1972, 2 voll.; ed. di I. Prado Pastore, Lima, 1974-1981, 6 voll.);&nbsp;T. de Herrera,&nbsp;&nbsp;<em>Alphabetum augustinianum,&nbsp;<\/em>T.&nbsp;I, Matriti, 1644, pp.&nbsp;387-388 (nuova ed., Roma, 1990);&nbsp;G. Monti,&nbsp;&nbsp;<em>Ristretto delle vite degli huomini e delle illustri en santit\u00e1 [&#8230;] dell&#8217;Ordine Agostiniano,&nbsp;<\/em>&nbsp;Bologna, 1647;&nbsp;S. Portillo,&nbsp;&nbsp;<em>Cr\u00f3nica Espiritual Agustiniana,&nbsp;<\/em>&nbsp;Madrid, 1651 e 1732;&nbsp;T. de Herrera,&nbsp;&nbsp;<em>Storia del Convento di San Agust\u00edn de Salamanca,&nbsp;<\/em>&nbsp;Madrid, 1652, pp.&nbsp;42, 56-78 e 151;&nbsp;B. de Torres,&nbsp;&nbsp;<em>Cr\u00f3nicas Agustinianas del Per\u00fa,&nbsp;<\/em>&nbsp;Lima, 1653 (a cura di M. Merino, Madrid, 1972, 2 voll.; a cura di I. Prado Pastor, Lima, 1974, 3 voll.);&nbsp;C. Antoniani,&nbsp;&nbsp;<em>Relatio Rec. mem.&nbsp;Cardinalis Antoniani super vita, sanctitate et miraculis Beati Joannis a Sancto Facundo Religiosi ordinis S. Augustini,&nbsp;<\/em>&nbsp;Romae, 1657;&nbsp;<em>Congregatione Sacrorum Rituum, Sive eminentisimo ac Rmo.D.Card.&nbsp;Aragonio.&nbsp;Salamtina, canonizationis Beati Joannis a Sancto Facundo ordinis Sancti Agustini.&nbsp;Positio super dubio: An constet de virtutibus Theologalibus, Fide, Spe, Charitate.&nbsp;In casu et ad effectum de quo agitur,&nbsp;<\/em>&nbsp;Romae, 1665;&nbsp;S. Castelblanco,&nbsp;&nbsp;<em>Virt\u00f9 e miracoli nella vita e nella morte del Beato Padre Fray Juan de Sah\u00fan [&#8230;],&nbsp;<\/em>&nbsp;Madrid, 1669;&nbsp;O. Quaranta,&nbsp;&nbsp;<em>Vita del Beato Giovanni di San Facondo, dell&#8217;Ordine de Santo Agostino,&nbsp;<\/em>&nbsp;Roma, 1673;&nbsp;G. Ortiz Gallardo,&nbsp;&nbsp;<em>Esposizione panegirica [&#8230;] con cui solennizz\u00f2 la canonizzazione di S. Juan de Sahag\u00fan,&nbsp;<\/em>&nbsp;Salamanca, 1679;&nbsp;L. Torelli,&nbsp;&nbsp;<em>Secoli agostiniani,&nbsp;<\/em>&nbsp;t.&nbsp;II, Bologna, 1682;&nbsp;Anonimo,&nbsp;&nbsp;<em>Compendium vitae [&#8230;] B. Joannis a S. Facundo,&nbsp;<\/em>&nbsp;Romae, 1690;&nbsp;JI de la Cruz, \u201cSonetti ed Endecha.&nbsp;Al retarde San Juan de Sahag\u00fan\u201d, a&nbsp;&nbsp;<em>Obras,&nbsp;<\/em>&nbsp;Messico, 1690;&nbsp;GA Valauri,&nbsp;&nbsp;<em>Vita de San Giovanni da San Facundo,&nbsp;<\/em>&nbsp;Roma, 1690;&nbsp;<em>Innocente<\/em>&nbsp;<em>cit.,&nbsp;<\/em>&nbsp;pp.&nbsp;385-400;&nbsp;G. Stefano,&nbsp;&nbsp;<em>Il politico cristiano [&#8230;] di San Giovanni da San Facondo, agostiniano,&nbsp;<\/em>&nbsp;Alessandria, 1691;&nbsp;A. de Witte,&nbsp;&nbsp;<em>Leven vanden H. Joannes a S. Facundo,&nbsp;<\/em>&nbsp;Anversa, 1691;&nbsp;E. Wolfgangus,&nbsp;&nbsp;<em>Vita Sancti Joannis a Facundo,&nbsp;<\/em>&nbsp;Monaco, 1691;&nbsp;N. Robine,&nbsp;&nbsp;<em>La vie de St. Jean Gon\u00e7alez de Sahag\u00fan, ou de saint Facond, religieux de l&#8217;Ordre de Saint Augustin,&nbsp;<\/em>&nbsp;Parigi, 1692;&nbsp;A. de Benavente,&nbsp;&nbsp;<em>Vita di San Juan de Sahag\u00fan,&nbsp;<\/em>&nbsp;Manila, 1698 (in lingua Pampanga);&nbsp;P. Manso,&nbsp;&nbsp;<em>Sermone in occasione dei solenni festeggiamenti che l&#8217;antico e maggiore Collegio S. Bartolom\u00e9 dell&#8217;Universit\u00e0 di Salamanca tenne nel rinnovamento della sua antica Cappella eretta per il suo illustre studente universitario, il glorioso S. Juan de Sahag\u00fan [&#8230; ],&nbsp;<\/em>&nbsp;Salamanca, 1709;&nbsp;S. Portillo e Aguilar,&nbsp;<em>Cronaca spirituale agostiniana,&nbsp;<\/em>&nbsp;t.&nbsp;II, Madrid, 1732;&nbsp;A. Hormosender,&nbsp;&nbsp;<em>Himmlische Eremiten-Schaar [&#8230;] des H. Vatters Augustini,&nbsp;<\/em>&nbsp;Vienna, 1733;&nbsp;G. Henschenio,&nbsp;&nbsp;<em>Acta Sanctorum Junii,&nbsp;<\/em>&nbsp;Venetiis, 1742, pp.&nbsp;616-663 (Bolandisti);&nbsp;M. Vidal,&nbsp;&nbsp;<em>Agostiniani di Salamanca.&nbsp;Storia del molto osservante convento S. Agust\u00edn NP di Salamanca,&nbsp;<\/em>&nbsp;t.&nbsp;I, Salamanca, 1751, pp.&nbsp;53-67;&nbsp;M. Vidal, M. Varona e JA \u00c1lvarez de Ribera, \u201cFeste celebrate a Salamanca nel 1691, in occasione della canonizzazione di San Giovanni di Sahag\u00fan\u201d, in&nbsp;&nbsp;<em>Agustinos de Salamanca, op.&nbsp;cit.,&nbsp;<\/em>&nbsp;t.&nbsp;II, pag.&nbsp;160-172;&nbsp;R. Escalona,&nbsp;&nbsp;<em>\u200b\u200bStoria del Monastero Reale di Sahag\u00fan,&nbsp;<\/em>&nbsp;Madrid, 1712;&nbsp;JF Ossinger,&nbsp;&nbsp;<em>Bibliographia Augustiniana,&nbsp;<\/em>&nbsp;Ingolstadii, 1768;&nbsp;B. Dorado,&nbsp;&nbsp;<em>Compendio storico della citt\u00e0 di Salamanca,&nbsp;<\/em>&nbsp;Salamanca, 1776;&nbsp;J. Interi\u00e1n de Ayala, \u201cIconografia di San Juan de Sahag\u00fan\u201d, in&nbsp;&nbsp;<em>Il pittore cristiano erudito,&nbsp;<\/em>&nbsp;Madrid, 1782, 2 voll.;&nbsp;MFJS (Monaco benedettino di Sahag\u00fan),&nbsp;&nbsp;<em>Vita del beato San Juan de Sahag\u00fan, detto Apostolo di Salamanca, ridotta a compendio con un breve resoconto dei suoi miracoli,&nbsp;<\/em>&nbsp;Le\u00f3n, 1857 e 1902;&nbsp;J. Croisett,&nbsp;&nbsp;<em>Anno cristiano,&nbsp;<\/em>&nbsp;t.&nbsp;III, Madrid, 1876, pp.&nbsp;995-1015;&nbsp;P. Guerin,&nbsp;&nbsp;<em>Saint Jean de Saint-Facond,&nbsp;<\/em>&nbsp;Parigi, 1885;&nbsp;A. Garc\u00eda-Maceira, \u201cSalmantine Legends: Fray Juan de Sahag\u00fan\u201d, e E. O rd\u00f3\u00f1ez y \u00c1lvarez de Castro, \u201cLas Reliquias de San Juan de Sahag\u00fan\u201d, in Revista&nbsp;&nbsp;<em>Agustiniana (RA)&nbsp;<\/em>&nbsp;[=&nbsp;<em>La Citt\u00e0 di Dio<\/em>&nbsp;], 12 (1886), pp.&nbsp;244-248 e pp.&nbsp;525-530, rispettivamente;&nbsp;M. Villar y Mac\u00edas,&nbsp;&nbsp;<em>Storia di Salamanca,&nbsp;<\/em>&nbsp;Salamanca, 1887;&nbsp;T. C\u00e1mara y Castro,&nbsp;&nbsp;<em>Vita di San Juan de Sah\u00fan [&#8230;], op.&nbsp;cit.&nbsp;<\/em>(ed. 1996);&nbsp;E. der Obren,&nbsp;&nbsp;<em>Leben des heilegen Johannes von Sahag\u00fan,&nbsp;<\/em>&nbsp;W\u00fcrzburg, 1892;&nbsp;A. Huarte y Echenique, \u201cL\u2019Universit\u00e0 di Salamanca e San Juan de Sahag\u00fan\u201d, in&nbsp;&nbsp;<em>Archivo Agustiniano (AA),&nbsp;<\/em>&nbsp;5 (1916), pp.&nbsp;17-24 e 437-439;&nbsp;W. Fern\u00e1ndez Luna,&nbsp;&nbsp;<em>Monografia storica di Sahag\u00fan e brevi notizie dei suoi illustri figli,&nbsp;<\/em>&nbsp;Le\u00f3n, 1920;&nbsp;G. de Santiago Vela, \u201cAtto con il quale Fr. Luis L\u00f3pez de Sol\u00eds, vescovo di Quito, eletto dal Chapas, si impegna a consegnare 2900 ducati dei 7000 che offr\u00ec per la canonizzazione di San Juan de Sahag\u00fan\u201d, in AA&nbsp;&nbsp;<em>,&nbsp;<\/em>&nbsp;14 (1920), pp.&nbsp;244-246;&nbsp;\u201cVoto della citt\u00e0 di Salamanca per celebrare la festa di San Juan de Sahag\u00fan\u201d, in&nbsp;&nbsp;<em>AA,&nbsp;<\/em>&nbsp;16 (1921), pp.&nbsp;241-243;&nbsp;\u00abLettere sulla canonizzazione di San Juan de Sahag\u00fan\u00bb, in&nbsp;&nbsp;<em>AA,&nbsp;<\/em>&nbsp;20 (1923), pp.&nbsp;355-356;&nbsp;<em>Saggio di una Biblioteca Iberoamericana dell&#8217;Ordine di Sant&#8217;Agostino,&nbsp;<\/em>T.&nbsp;VII, El Escorial, 1925, pp.&nbsp;7-24;&nbsp;PM Bordoy-Torrents, \u201cStudio sulle note bibliche di San Juan de Sahag\u00fan\u201d, in&nbsp;&nbsp;<em>AA,&nbsp;<\/em>&nbsp;43 (1935), pp.&nbsp;26-34;&nbsp;J. P\u00e9rez de Urbel, \u201cSan Juan de Sahag\u00fan\u201d, in&nbsp;&nbsp;<em>Toma y Lee&nbsp;<\/em>&nbsp;(Santiago del Cile), 17 (1940), pp.&nbsp;49-52;&nbsp;M. L\u00f3pez,&nbsp;&nbsp;<em>Tre religiosi illustri e molto eroici.&nbsp;San Juan de Sah\u00fan, V. Padre Diego Ortiz Ruiz, protomartire del Per\u00f9, e Agust\u00edn de Coru\u00f1a,&nbsp;<\/em>&nbsp;Lima, 1949;&nbsp;L. Camblor,&nbsp;&nbsp;<em>San Juan de Sahag\u00fan.&nbsp;La sua vita prodigiosa e i miracoli straordinari,&nbsp;<\/em>&nbsp;El Escorial, 1962 (ed. Palencia, 1997);&nbsp;G. D\u00edaz, \u201cSahag\u00fan, Juan de, OSA\u201d, in Q. Aldea Vaquero, T. Mar\u00edn Mart\u00ednez e J. Vives Gatell (dirs.),&nbsp;&nbsp;<em>Dizionario di storia ecclesiastica di Spagna,&nbsp;<\/em>&nbsp;t.&nbsp;IV, Madrid, Consiglio Superiore della Ricerca Scientifica, Istituto Enrique Fl\u00f3rez, 1975, p.&nbsp;2135;&nbsp;F. L\u00f3pez,&nbsp;&nbsp;<em>Vita e miracoli di San Juan de Sahag\u00fan, patrono principale di Salamanca,&nbsp;<\/em>&nbsp;Salamanca, Librer\u00eda Cervantes, 1979;&nbsp;JM Cuenca Coloma,&nbsp;&nbsp;<em>Sahag\u00fan, Monasterio e Villa.&nbsp;&#8216;La gloria pi\u00f9 eccellente della citt\u00e0&#8217;,&nbsp;<\/em>&nbsp;Valladolid, Estudio Agustiniano, 1985;&nbsp;\u00abIl Tesoro per la canonizzazione di San Juan de Sahag\u00fan\u00bb, in&nbsp;&nbsp;<em>AA,&nbsp;<\/em>&nbsp;69 (1985), pp.&nbsp;167-244;&nbsp;JM Bengoa,&nbsp;&nbsp;<em>I nostri santi agostiniani.&nbsp;Juan de Sahag\u00fan, seminatore di pace,&nbsp;<\/em>&nbsp;Marcilla, 1991;&nbsp;G. Mart\u00ednez, \u201cPia Opera di canonizzazione di San Juan de Sahag\u00fan e beatificazione di Padre Fray Alonso de Orozco\u201d, in&nbsp;&nbsp;<em>RA,&nbsp;<\/em>&nbsp;32 (1991), pp.&nbsp;1199-1259;&nbsp;U. Chevalier, \u201cJean de Sahag\u00fan\u201d, in FW Bautz (a cura di),&nbsp;&nbsp;<em>Biographisch-bibliographisches Kirchenlexikon.&nbsp;III: Jedin, H. bis Kleinschmidt, B.,&nbsp;<\/em>&nbsp;Herzberg, 1992;&nbsp;A. Garc\u00eda Abad,&nbsp;&nbsp;<em>San Juan de Sah\u00fan: fenomeno sociale del XV secolo,&nbsp;<\/em>&nbsp;Le\u00f3n, Lancia, 1994;&nbsp;M. S\u00e1nchez,&nbsp;&nbsp;<em>Appunti per la storia della chiesa parrocchiale di San Juan de Sah\u00fan de Salamanca: primo centenario (1895-1995),&nbsp;<\/em>&nbsp;Salamanca, Obispado, 1995;&nbsp;Anonimo,&nbsp;&nbsp;<em>Novena in onore di San Juan de Sahag\u00fan,&nbsp;<\/em>&nbsp;Salamanca, 1997;&nbsp;P. Luna,&nbsp;&nbsp;<em>San Juan de Sahag\u00fan, angelo della pace,&nbsp;<\/em>&nbsp;Madrid, Revista Agustiniana, 1998 [in particolare, \u201cIconografia di San Juan de Sahag\u00fan\u201d, pp.&nbsp;85-90];&nbsp;R. Lazcano, \u201cSan Juan de Sahag\u00fan\u201d, in C. Leonardi, A Riccardi e G. Z arri (dirs.),&nbsp;&nbsp;<em>Diccionario de los Santos,&nbsp;<\/em>&nbsp;t.&nbsp;I, Madrid, 2000, pp.&nbsp;1347-1349;&nbsp;JL Repetto Beyes, \u201cSan Juan de Sahag\u00fan\u201d, in JA Mart\u00ednez Puche (dir.),&nbsp;&nbsp;<em>Nuovo Anno Cristiano,&nbsp;<\/em>&nbsp;t.&nbsp;VI, Madrid, Edibesa, 2001, pp.&nbsp;283-288;&nbsp;P. Bellini, \u201cSan Juan de Sahag\u00fan\u201d, in F. Rojo (dir.),&nbsp;&nbsp;<em>La seduzione di Dio,&nbsp;<\/em>&nbsp;Roma, 2001, pp.&nbsp;125-127;&nbsp;F. Ba\u00f1os Vallejo,&nbsp;&nbsp;<em>Le vite dei santi nella letteratura spagnola medievale,&nbsp;<\/em>Madrid, 2003, pp.&nbsp;99-102;&nbsp;J. \u00c1lvarez Maestro, \u201cSan Juan de Sahag\u00fan\u201d, in&nbsp;&nbsp;<em>I santi di ogni giorno: anno cristiano agostiniano,&nbsp;<\/em>&nbsp;Madrid, Revista Agustiniana, 2004, pp.&nbsp;228-229;&nbsp;V. Cap\u00e1naga, \u201cSan Juan de Sahag\u00fan\u201d, in&nbsp;&nbsp;<em>Anno Cristiano&nbsp;<\/em>&nbsp;(Madrid), t.&nbsp;VI (2004), pp.&nbsp;270-277.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Francisco Javier Campos e Fern\u00e1ndez de Sevilla, OSA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pozo Amarillo, era un pozzo nel quale ai tempi del santo cadde un fanciullo. Il pozzo era profondo ma Juan vi gett\u00f2 la sua cintura: l&#8217;acqua sal\u00ec fino a permettere al piccolo di aggrapparsi ad essa e salvarsi. San Juan de Sahagunsacerdote eremita agostiniano (1430-1479) Juan de Sahagun, San&nbsp;.&nbsp;Apostolo di Salamanca&nbsp;.&nbsp;Sahag\u00fan (Le\u00f3n), 1429-1431 \u2013 Salamanca, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":6,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12044","post","type-post","status-publish","format-standard","hentry","category-senza-categoria"],"_links":{"self":[{"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/posts\/12044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/comments?post=12044"}],"version-history":[{"count":5,"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/posts\/12044\/revisions"}],"predecessor-version":[{"id":12090,"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/posts\/12044\/revisions\/12090"}],"wp:attachment":[{"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/media?parent=12044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/categories?post=12044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/santagostinorimini.it\/new_sito\/wp-json\/wp\/v2\/tags?post=12044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}